{"id":180,"count":2,"description":"","link":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/","name":"CBD","slug":"cbd-2","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CBD Archive - Journal of Public Health Research<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CBD Archive - Journal of Public Health Research\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Journal of Public Health Research\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/\",\"url\":\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/\",\"name\":\"CBD Archive - Journal of Public Health Research\",\"isPartOf\":{\"@id\":\"https:\/\/www.jphres.us.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.jphres.us.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CBD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jphres.us.com\/#website\",\"url\":\"https:\/\/www.jphres.us.com\/\",\"name\":\"Journal of Public Health Research\",\"description\":\"The Journal of Public Health Research is an online Open Access, peer-reviewed journal in the field of public health science. The scope of the journal is to stimulate debate and spreading of knowledge in this area in order to improve public health.\",\"publisher\":{\"@id\":\"https:\/\/www.jphres.us.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jphres.us.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.jphres.us.com\/#organization\",\"name\":\"Journal of Public Health Research\",\"url\":\"https:\/\/www.jphres.us.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.jphres.us.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.jphres.us.com\/wp-content\/uploads\/2022\/10\/Favicon-JPHRES.png\",\"contentUrl\":\"https:\/\/www.jphres.us.com\/wp-content\/uploads\/2022\/10\/Favicon-JPHRES.png\",\"width\":150,\"height\":114,\"caption\":\"Journal of Public Health Research\"},\"image\":{\"@id\":\"https:\/\/www.jphres.us.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.citefactor.org\/journal\/index\/5410\/journal-of-public-health-research#.ZD-hS-xBx3k\",\"https:\/\/www.scimagojr.com\/journalsearch.php?q=21100790524&amp;amp;tip=sid&amp;amp;clean=0\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CBD Archive - Journal of Public Health Research","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/","og_locale":"es_ES","og_type":"article","og_title":"CBD Archive - Journal of Public Health Research","og_url":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/","og_site_name":"Journal of Public Health Research","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/","url":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/","name":"CBD Archive - Journal of Public Health Research","isPartOf":{"@id":"https:\/\/www.jphres.us.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jphres.us.com\/es\/index.php\/category\/cbd-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.jphres.us.com\/es\/"},{"@type":"ListItem","position":2,"name":"CBD"}]},{"@type":"WebSite","@id":"https:\/\/www.jphres.us.com\/#website","url":"https:\/\/www.jphres.us.com\/","name":"Journal of Public Health Research","description":"The Journal of Public Health Research is an online Open Access, peer-reviewed journal in the field of public health science. The scope of the journal is to stimulate debate and spreading of knowledge in this area in order to improve public health.","publisher":{"@id":"https:\/\/www.jphres.us.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jphres.us.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.jphres.us.com\/#organization","name":"Journal of Public Health Research","url":"https:\/\/www.jphres.us.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.jphres.us.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.jphres.us.com\/wp-content\/uploads\/2022\/10\/Favicon-JPHRES.png","contentUrl":"https:\/\/www.jphres.us.com\/wp-content\/uploads\/2022\/10\/Favicon-JPHRES.png","width":150,"height":114,"caption":"Journal of Public Health Research"},"image":{"@id":"https:\/\/www.jphres.us.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.citefactor.org\/journal\/index\/5410\/journal-of-public-health-research#.ZD-hS-xBx3k","https:\/\/www.scimagojr.com\/journalsearch.php?q=21100790524&amp;amp;tip=sid&amp;amp;clean=0"]}]}},"_links":{"self":[{"href":"https:\/\/www.jphres.us.com\/es\/index.php\/wp-json\/wp\/v2\/categories\/180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jphres.us.com\/es\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.jphres.us.com\/es\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.jphres.us.com\/es\/index.php\/wp-json\/wp\/v2\/posts?categories=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}